{"id":1420,"date":"2023-03-22T05:30:40","date_gmt":"2023-03-22T05:30:40","guid":{"rendered":"https:\/\/demo.bravisthemes.com\/jackcerra\/?page_id=1420"},"modified":"2023-03-22T05:30:40","modified_gmt":"2023-03-22T05:30:40","slug":"team-details","status":"publish","type":"page","link":"https:\/\/premiumsolutions.qa\/ar\/team-details\/","title":{"rendered":"Team Details"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1420\" class=\"elementor elementor-1420\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2896fc pxl-row-scroll-fixed elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-section-overflow-visible pxl-bg-color-none pxl-section-overlay-none\" data-id=\"d2896fc\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                    <div class=\"elementor-row\">\n                <div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-010c27a pxl-column-sticky\" data-id=\"010c27a\" data-element_type=\"column\">\r\n            <div class=\"elementor-column-wrap elementor-element-populated\">\r\n                                        <div class=\"elementor-widget-wrap\">\r\n                \t\t<div class=\"elementor-element elementor-element-8521d0a elementor-widget elementor-widget-pxl_image\" data-id=\"8521d0a\" data-element_type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-8521d0a-9385\" class=\"pxl-image-single  style-default\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                                <div class=\"pxl-item--image\" data-parallax-value=\"\">\r\n                                                    <img fetchpriority=\"high\" decoding=\"async\" width=\"470\" height=\"534\" src=\"https:\/\/premiumsolutions.qa\/wp-content\/uploads\/2023\/03\/team-single.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                            <\/div>\r\n                            \r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d311c elementor-widget elementor-widget-pxl_heading\" data-id=\"58d311c\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-58d311c-4207\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\tJackson Miller\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c633985 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"c633985\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tConsultant\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b174e3e elementor-widget elementor-widget-pxl_text_editor\" data-id=\"b174e3e\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tEmail Address\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3400ddd elementor-widget elementor-widget-pxl_text_editor\" data-id=\"3400ddd\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tjacksonmiller@email.com\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef8122 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"1ef8122\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tPhone Number\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89a3ea7 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"89a3ea7\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t+123 456 78999\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4653ecb elementor-widget elementor-widget-pxl_text_editor\" data-id=\"4653ecb\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tAddress\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea867e1 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"ea867e1\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>231, Utah Downtown Mall, USA<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b64a1 elementor-widget elementor-widget-pxl_icon\" data-id=\"c8b64a1\" data-element_type=\"widget\" data-widget_type=\"pxl_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-icon-list pxl-icon1 style-box1\" data-wow-delay=\"ms\">\r\n                                    <a class=\"elementor-repeater-item-85c3fb3 ps-top\" href=\"#\">\r\n                    <i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>                                            <span>\u0641\u064a\u0633\u0628\u0648\u0643<\/span>\r\n                                    <\/a>\r\n                                                <a class=\"elementor-repeater-item-ce968ee ps-top\" href=\"#\">\r\n                    <i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>                                            <span>Twitter<\/span>\r\n                                    <\/a>\r\n                                                <a class=\"elementor-repeater-item-4a8a011 ps-top\" href=\"#\">\r\n                    <i aria-hidden=\"true\" class=\"fab fa-pinterest\"><\/i>                                            <span>Pinterest<\/span>\r\n                                    <\/a>\r\n                                                <a class=\"elementor-repeater-item-f020027 ps-top\" href=\"#\">\r\n                    <i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>                                            <span>\u0644\u064a\u0646\u0643\u062f \u0627\u0646<\/span>\r\n                                    <\/a>\r\n                                                <a class=\"elementor-repeater-item-f687dcc ps-top\" href=\"#\">\r\n                    <i aria-hidden=\"true\" class=\"fab fa-behance\"><\/i>                                            <span>Behance<\/span>\r\n                                    <\/a>\r\n                        <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t        <div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-6311775 pxl-column-none\" data-id=\"6311775\" data-element_type=\"column\">\r\n            <div class=\"elementor-column-wrap elementor-element-populated\">\r\n                                        <div class=\"elementor-widget-wrap\">\r\n                \t\t<div class=\"elementor-element elementor-element-e2f1665 elementor-widget elementor-widget-pxl_heading\" data-id=\"e2f1665\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-e2f1665-4472\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\tWork Experience\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3ddc6c elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d3ddc6c\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tOur Senior Consultants bring their real-world business experience to you. They are successful former CEOs and entrepreneurs who work with you on business strategy and implementation. Each MAP Senior Consultant has transitioned from a successful career, to a higher calling helping others succeed.\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d25d9e elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-section-overflow-visible pxl-bg-color-none pxl-section-overlay-none\" data-id=\"2d25d9e\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                    <div class=\"elementor-row\">\n                <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7a10134 pxl-column-none\" data-id=\"7a10134\" data-element_type=\"column\">\r\n            <div class=\"elementor-column-wrap elementor-element-populated\">\r\n                                        <div class=\"elementor-widget-wrap\">\r\n                \t\t<div class=\"elementor-element elementor-element-6fe77a5 elementor-widget__width-auto elementor-widget elementor-widget-pxl_list\" data-id=\"6fe77a5\" data-element_type=\"widget\" data-widget_type=\"pxl_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-list pxl-list1\">\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Work Experience 1<\/div>\r\n            <\/div>\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Work Experience 2<\/div>\r\n            <\/div>\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Work Experience 3<\/div>\r\n            <\/div>\r\n            <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1420a elementor-widget__width-auto elementor-widget elementor-widget-pxl_list\" data-id=\"9a1420a\" data-element_type=\"widget\" data-widget_type=\"pxl_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-list pxl-list1\">\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Work Experience 4<\/div>\r\n            <\/div>\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Work Experience 5<\/div>\r\n            <\/div>\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Work Experience 6<\/div>\r\n            <\/div>\r\n            <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-299e700 elementor-widget elementor-widget-pxl_heading\" data-id=\"299e700\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-299e700-9733\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\tConsultation Process\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0741a7f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0741a7f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8723c5 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d8723c5\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t\n\nThe MAP Vital Factors Team is comprised of individuals with extensive experience. Each team member has a significant number of years of experience in executive and leadership positions with multinational companies and entrepreneurial driven organizations large.\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e277dfc elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-section-overflow-visible pxl-bg-color-none pxl-section-overlay-none\" data-id=\"e277dfc\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                    <div class=\"elementor-row\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-671e208 pxl-column-none\" data-id=\"671e208\" data-element_type=\"column\">\r\n            <div class=\"elementor-column-wrap elementor-element-populated\">\r\n                                        <div class=\"elementor-widget-wrap\">\r\n                \t\t<div class=\"elementor-element elementor-element-741b6fe elementor-widget elementor-widget-pxl_process\" data-id=\"741b6fe\" data-element_type=\"widget\" data-widget_type=\"pxl_process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-process pxl-process1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n                    <div class=\"pxl-item--step pxl-mr-26\">\r\n                1            <\/div>\r\n                <div class=\"pxl-item--meta\">\r\n\t        <h5 class=\"pxl-item--title el-empty\">First appointment<\/h5>\r\n\t        <div class=\"pxl-item--description el-empty\">We understand the importance of approaching each work integrally and believe.<\/div>\r\n\t\t<\/div>    \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a26a7 elementor-widget elementor-widget-pxl_process\" data-id=\"46a26a7\" data-element_type=\"widget\" data-widget_type=\"pxl_process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-process pxl-process1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n                    <div class=\"pxl-item--step pxl-mr-26\">\r\n                3            <\/div>\r\n                <div class=\"pxl-item--meta\">\r\n\t        <h5 class=\"pxl-item--title el-empty\">Project Brief<\/h5>\r\n\t        <div class=\"pxl-item--description el-empty\">Design studio founded in London and expanded our services, and become.<\/div>\r\n\t\t<\/div>    \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t        <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6cb8815 pxl-column-none\" data-id=\"6cb8815\" data-element_type=\"column\">\r\n            <div class=\"elementor-column-wrap elementor-element-populated\">\r\n                                        <div class=\"elementor-widget-wrap\">\r\n                \t\t<div class=\"elementor-element elementor-element-75afef6 elementor-widget elementor-widget-pxl_process\" data-id=\"75afef6\" data-element_type=\"widget\" data-widget_type=\"pxl_process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-process pxl-process1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n                    <div class=\"pxl-item--step pxl-mr-26\">\r\n                2            <\/div>\r\n                <div class=\"pxl-item--meta\">\r\n\t        <h5 class=\"pxl-item--title el-empty\">Campeign Design<\/h5>\r\n\t        <div class=\"pxl-item--description el-empty\">Don\u2019t worry about any thing, our security experts will install your new system, activate it.<\/div>\r\n\t\t<\/div>    \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76f08bf elementor-widget elementor-widget-pxl_process\" data-id=\"76f08bf\" data-element_type=\"widget\" data-widget_type=\"pxl_process.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-process pxl-process1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n                    <div class=\"pxl-item--step pxl-mr-26\">\r\n                4            <\/div>\r\n                <div class=\"pxl-item--meta\">\r\n\t        <h5 class=\"pxl-item--title el-empty\">Exit Strategy<\/h5>\r\n\t        <div class=\"pxl-item--description el-empty\">Rounding up a bunch of specific designs & talking about the merits.<\/div>\r\n\t\t<\/div>    \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e97a7ae elementor-widget elementor-widget-pxl_heading\" data-id=\"e97a7ae\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-e97a7ae-5001\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\tProfessional Skills\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52fb136 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52fb136\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e358ad elementor-widget elementor-widget-pxl_text_editor\" data-id=\"3e358ad\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tOur Executive Consultants are hands-on business developers whose focus is to establish relationships with new clients and then connect them.\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00a6b12 elementor-widget elementor-widget-pxl_progressbar\" data-id=\"00a6b12\" data-element_type=\"widget\" data-widget_type=\"pxl_progressbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-progressbar pxl-progressbar-1\">\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\n                <h5 class=\"pxl--title el-empty pxl-mr-20\">Consultency<\/h5>\n                <div class=\"pxl--holder\">\n                    <div class=\"pxl--progressbar\" role=\"progressbar\" data-valuetransitiongoal=\"92\">\n                        <div class=\"pxl--percentage\">92%<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\n                <h5 class=\"pxl--title el-empty pxl-mr-20\">Finance<\/h5>\n                <div class=\"pxl--holder\">\n                    <div class=\"pxl--progressbar\" role=\"progressbar\" data-valuetransitiongoal=\"85\">\n                        <div class=\"pxl--percentage\">85%<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\n                <h5 class=\"pxl--title el-empty pxl-mr-20\">Corporate Business<\/h5>\n                <div class=\"pxl--holder\">\n                    <div class=\"pxl--progressbar\" role=\"progressbar\" data-valuetransitiongoal=\"75\">\n                        <div class=\"pxl--percentage\">75%<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa4d2cc elementor-widget elementor-widget-pxl_heading\" data-id=\"aa4d2cc\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-aa4d2cc-7944\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\tAwards\t\t\n\t\t<\/h3>\n\n\t\t\n\t\t\n\t\t\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b400c6f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b400c6f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e107d2 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"4e107d2\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\tLong-term, Executive Consultants continually assess client needs, make recommendations on consulting services.\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c62e4d elementor-widget__width-auto elementor-widget elementor-widget-pxl_list\" data-id=\"9c62e4d\" data-element_type=\"widget\" data-widget_type=\"pxl_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-list pxl-list1\">\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Employee of the month<\/div>\r\n            <\/div>\r\n            <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1000719 elementor-widget__width-auto elementor-widget elementor-widget-pxl_list\" data-id=\"1000719\" data-element_type=\"widget\" data-widget_type=\"pxl_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-list pxl-list1\">\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Best Consultant 2022<\/div>\r\n            <\/div>\r\n            <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e19e59f elementor-widget__width-auto elementor-widget elementor-widget-pxl_list\" data-id=\"e19e59f\" data-element_type=\"widget\" data-widget_type=\"pxl_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-list pxl-list1\">\r\n                    <div class=\"pxl--item\" data-wow-delay=\"ms\">\r\n                                    <div class=\"pxl-item--icon pxl-mr-8\">\r\n                        <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                    <\/div>\r\n                                <div class=\"pxl-item--text el-empty\">Best Employee 2021<\/div>\r\n            <\/div>\r\n            <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jackson Miller Consultant Email Address jacksonmiller@email.com Phone Number +123 456 78999 Address 231, Utah Downtown Mall, USA Facebook Twitter Pinterest Linkedin Behance Work Experience Our Senior Consultants bring their real-world business experience to you. They are successful former CEOs and entrepreneurs who work with you on business strategy and implementation. Each MAP Senior Consultant has [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-1420","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/pages\/1420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/comments?post=1420"}],"version-history":[{"count":0,"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/pages\/1420\/revisions"}],"wp:attachment":[{"href":"https:\/\/premiumsolutions.qa\/ar\/wp-json\/wp\/v2\/media?parent=1420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}